
{"id":720,"date":"2009-05-21T09:01:30","date_gmt":"2009-05-21T08:01:30","guid":{"rendered":"http:\/\/elsa-fachinetti.fr\/blog\/?p=720"},"modified":"2009-05-21T09:01:30","modified_gmt":"2009-05-21T08:01:30","slug":"nouvelle-adresse","status":"publish","type":"post","link":"http:\/\/elsa-fachinetti.fr\/blog\/nouvelle-adresse\/","title":{"rendered":"Nouvelle adresse !"},"content":{"rendered":"<p>Et voil\u00e0 mon premier article sur <strong>www.mikan.fr\/blog<\/strong>, h\u00e9berg\u00e9 par 1and1 ! Contrairement\u00a0 \u00e0 ce dont je m&rsquo;attendais, la migration a \u00e9t\u00e9 tr\u00e8s facile et tr\u00e8s rapide, c&rsquo;est d\u00e9j\u00e0 une bonne chose. Pour ceux qui se demanderaient \u00ab\u00a0pourquoi www.mikan.fr et non www.mandarine.fr ?\u00a0\u00bb, la r\u00e9ponse est simple : www.mandarine.fr \u00e9tait d\u00e9j\u00e0 pris. Et comme je voulais quelque chose de court, j&rsquo;ai choisi \u00ab\u00a0mikan\u00a0\u00bb qui signifie&#8230; (Tadaaa !) <strong>Mandarine, en japonais<\/strong>.<\/p>\n<p>Justement, en parlant de Japonais, je souhaite commencer un autre blog sur tout ce qui touche \u00e0 la <strong>culture japonaise<\/strong> (mangas, anim\u00e9s, mais aussi f\u00eates, traditions, plats typiques, etc).<\/p>\n<p>Voil\u00e0 pour les nouvelles, et n&rsquo;oubliez pas de vous mettre \u00e0 jour en enregistrant le <strong>nouveau flux rss<\/strong> : <strong><a href=\"http:\/\/elsa-fachinetti.fr\/blog\/feed\/\" target=\"_blank\">http:\/\/elsa-fachinetti.fr\/blog\/feed\/<\/a> <\/strong>!<\/p>\n<p>Changeons de sujet : je ne pourrai pas poster dans les prochains jours puisque<strong> je participe au FF1J (Festival du Film d&rsquo;1 jour)<\/strong>, pas en tant que que concurrente mais<strong> en tant que bloggeuse<\/strong> ! Je posterai donc sur ce blog : <strong><a href=\"http:\/\/ae.utbm.fr\/ff1j\/blog.php\">Blog du FF1J<\/a><\/strong>. Le festival commence ce matin, (11h) et se terminera samedi soir. Les films seront ensuite projet\u00e9 au cin\u00e9ma M\u00e9garama d&rsquo;Audincourt. Pour en savoir plus, rendez-vous sur le <a href=\"http:\/\/ae.utbm.fr\/ff1j\/blog.php\" target=\"_blank\">blog<\/a> et sur <a href=\"http:\/\/twitter.com\/FF1J\" target=\"_blank\">twitter<\/a> ! Et puis, je pense faire un point sur ce blog quand le festival sera termin\u00e9.<\/p>\n<p style=\"text-align:center\"><object width=\"500\" height=\"281\" data=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=4737604&amp;server=vimeo.com&amp;show_title=1&amp;show_byline=1&amp;show_portrait=0&amp;color=ffffff&amp;fullscreen=1\" type=\"application\/x-shockwave-flash\"><param name=\"allowfullscreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/vimeo.com\/moogaloop.swf?clip_id=4737604&amp;server=vimeo.com&amp;show_title=1&amp;show_byline=1&amp;show_portrait=0&amp;color=ffffff&amp;fullscreen=1\" \/><\/object><\/p>\n<p><a href=\"http:\/\/vimeo.com\/4737604\">Jingle Festival du Film d&rsquo;Un Jour 2009<\/a> from <a href=\"http:\/\/vimeo.com\/skiplecariboo\">Thomas Charbit<\/a> on <a href=\"http:\/\/vimeo.com\">Vimeo<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Et voil\u00e0 mon premier article sur www.mikan.fr\/blog, h\u00e9berg\u00e9 par 1and1 ! Contrairement\u00a0 \u00e0 ce dont je m&rsquo;attendais, la migration a \u00e9t\u00e9 tr\u00e8s facile \n<a class=\"moretag\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/nouvelle-adresse\/\"> [...]<\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[14,189],"tags":[194,41,198,197,193,195],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/720"}],"collection":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":0,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/720\/revisions"}],"wp:attachment":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/categories?post=720"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/tags?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}