
{"id":4048,"date":"2020-12-11T18:42:34","date_gmt":"2020-12-11T16:42:34","guid":{"rendered":"http:\/\/elsa-fachinetti.fr\/blog\/?p=4048"},"modified":"2021-08-18T17:02:59","modified_gmt":"2021-08-18T15:02:59","slug":"jane-eyre-charlotte-bronte","status":"publish","type":"post","link":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/","title":{"rendered":"\u00ab\u00a0Jane Eyre\u00a0\u00bb de Charlotte Bront\u00eb : romance et allumettes"},"content":{"rendered":"<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-4049\" src=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920-595x397.jpg\" alt=\"\" width=\"595\" height=\"397\" srcset=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920-595x397.jpg 595w, http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920-768x512.jpg 768w, http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920-960x640.jpg 960w, http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920.jpg 1920w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/>\r\n\r\nApr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j&rsquo;avais envie de r\u00eaver un peu. C&rsquo;est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu&rsquo;est Jane Eyre de Charlotte Bront\u00eb.\r\n\r\nLa premi\u00e8re fois que j&rsquo;ai lu ce roman, c&rsquo;\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de pr\u00e9ciser que je n&rsquo;en ai pas gard\u00e9 un grand souvenir. Retour sur cette seconde lecture, en fran\u00e7ais dans le texte.\r\n\r\n\r\n\r\n \r\n<h2 class=\"wp-block-heading\">\u00c7a parle de quoi ?<\/h2>\r\n \r\n\r\nIl y a ceux qui naissent sous une bonne \u00e9toile et il y a les autres. Les gens comme Jane Eyre par exemple. Recueillie tr\u00e8s jeune par sa tante apr\u00e8s la mort de ses parents, elle est rejet\u00e9e et maltrait\u00e9e par sa famille d&rsquo;adoption. Elle n&rsquo;a que 10 ans lorsque, \u00e0 la suite d&rsquo;une punition injuste, elle se rebelle violemment et est envoy\u00e9e \u00e0 Lowood, un internat intransigeant qui impose \u00e0 ses pensionnaires le d\u00e9nuement le plus total.\r\nLes conditions de vie sont rudes et nombre d&rsquo;\u00e9l\u00e8ves sont bient\u00f4t terrass\u00e9es par une \u00e9pid\u00e9mie de typhus, au cours de laquelle Jane perd sa meilleure amie. Une catastrophe qui donne toutefois un peu de r\u00e9pit \u00e0 la jeune fille : l&rsquo;ampleur du drame scandalise l&rsquo;opinion publique et oblige le propri\u00e9taire \u00e0 rendre le quotidien de ses pensionnaires un peu plus confortable.\r\n\r\n \r\n\r\nNotre h\u00e9ro\u00efne passera 8 ans \u00e0 Lowood, d&rsquo;abord en tant que pensionnaire puis en tant qu&rsquo;enseignante. Le temps a fait d&rsquo;elle une jeune femme sage et vertueuse mais elle n&rsquo;a pas renonc\u00e9 \u00e0 son caract\u00e8re bien tremp\u00e9. A 18 ans, elle d\u00e9cide de prendre son envol et trouve une place au\u00a0ch\u00e2teau de Thornfield-Hall o\u00f9 elle devient la pr\u00e9ceptrice de la p\u00e9tillante Ad\u00e8le, une petite Fran\u00e7aise. C&rsquo;est l\u00e0 qu&rsquo;elle fait la rencontre du propri\u00e9taire des lieux, Mr. Rochester, un quarantenaire secret et taciturne qui ne la laisse pas indiff\u00e9rente.\r\nUne vie plus agr\u00e9able s&rsquo;offre enfin \u00e0 Jane, mais le manoir semble renfermer quelque obscur myst\u00e8re. Quel est donc ce rire d\u00e9ment qui r\u00e9sonne parfois dans ses couloirs ?\r\n\r\n \r\n<h2 class=\"wp-block-heading\">J&rsquo;en pense quoi ?<\/h2>\r\n \r\n\r\nComme je l&rsquo;ai dit, je ne gardais pas grand souvenir de ce<em> Jane Eyre<\/em>. Ce fut donc une red\u00e9couverte totale de ce roman consid\u00e9r\u00e9 comme une r\u00e9f\u00e9rence du genre. C&rsquo;est bien simple, tous les ingr\u00e9dients du romantisme sont l\u00e0 : la jeune femme prude et pieuse qui refoule ses sentiments, l&rsquo;homme m\u00fbr t\u00e9n\u00e9breux, le vaste manoir isol\u00e9&#8230; le tout enrob\u00e9 dans un XVIII\u00e8me si\u00e8cle aux joutes oratoires \u00e9loquentes et aux robes de bal somptueuses.\r\n\r\n \r\n\r\nA ma grande surprise, j&rsquo;ai bien aim\u00e9. D&rsquo;ordinaire, je lis assez peu de romans sentimentaux. Je pr\u00e9f\u00e8re l&rsquo;action, le suspense, l&rsquo;aventure&#8230; Sans doute ma curiosit\u00e9 a-t-elle \u00e9t\u00e9 titill\u00e9e par le myst\u00e8re induit par les rires gla\u00e7ants et les ombres mena\u00e7antes qui s&rsquo;invitent rapidement dans le quotidien de Jane. La relation que vont entretenir Jane et Mr. Rochester, platonique, pure, a fait le reste.\r\nPourtant, force est de reconna\u00eetre que les protagonistes m&rsquo;ont inspir\u00e9e peu d&#8217;empathie, notamment Jane qui, enferm\u00e9e dans ses principes et sa vertu, prend parfois des d\u00e9cisions incompr\u00e9hensibles. Autre \u00e9poque, autres m\u0153urs, dira-t-on. La jeune femme est ce qu&rsquo;on appellerait aujourd&rsquo;hui une \u00ab\u00a0control-freak\u00a0\u00bb : ultra-rigide tout au long du roman, elle ne s&rsquo;autorise que peu d&rsquo;\u00e9carts. Il est donc difficile de la trouver sympathique.\r\n\r\n \r\n\r\nDe mani\u00e8re g\u00e9n\u00e9rale, les personnages sont plut\u00f4t froids, dans la retenue permanente. Une attitude qui n&rsquo;a rien de surprenant dans le contexte de la Haute soci\u00e9t\u00e9 britannique du XVIII\u00e8me si\u00e8cle mais qui m&rsquo;a emp\u00each\u00e9e de quitter cette place de simple spectatrice pour m&rsquo;impliquer plus avant dans l&rsquo;histoire. Comme je ne veux pas spolier, je dirai simplement que peu importe l&rsquo;issue du roman, je l&rsquo;aurais appr\u00e9ci\u00e9e de la m\u00eame fa\u00e7on. Je n&rsquo;ai \u00e9t\u00e9 ni d\u00e9\u00e7ue, ni combl\u00e9e par les \u00e9v\u00e9nements qui ponctuent la vie de Jane. Ils se sont produits, voil\u00e0 tout.\r\n\r\n \r\n\r\nReste que, comme je l&rsquo;ai dit, j&rsquo;ai aim\u00e9. Bien que le roman soit plut\u00f4t contemplatif et lent, la vie de notre h\u00e9ro\u00efne est suffisamment int\u00e9ressante pour maintenir l&rsquo;int\u00e9r\u00eat du lecteur et j&rsquo;ai pris beaucoup de plaisir \u00e0 voyager dans le temps \u00e0 ses c\u00f4t\u00e9s pendant quelques heures. Le temps s&rsquo;\u00e9coule tranquillement mais s\u00fbrement, avec son lot de petits \u00e9v\u00e9nements quotidiens.\r\n\r\n \r\n\r\nAlors si vous \u00eates d&rsquo;humeur fleur bleue et voulez vous \u00e9vader un peu, loin de notre quotidien effervescent et sur-connect\u00e9, offrez-vous ce <em>Jane Eyre<\/em>, installez-vous confortablement au fond de votre fauteuil, faites une place au chat et lancez-vous&#8230;\r\n\r\n \r\n<h2 class=\"wp-block-heading\">En bref<\/h2>\r\n \r\n<ul>\r\n \t<li>J&rsquo;ai aim\u00e9 : la romance pure entre Jane et Mr. Rochester, le myst\u00e8re qui entoure Thornfield-Hall, le cadre historique du XVIII\u00e8me si\u00e8cle<\/li>\r\n \t<li>J&rsquo;ai moins aim\u00e9 : le caract\u00e8re et l&rsquo;attitude de Jane, qui r\u00e9duisent consid\u00e9rablement son capital sympathie<\/li>\r\n<\/ul>\r\n","protected":false},"excerpt":{"rendered":"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j&rsquo;avais envie de r\u00eaver un peu. C&rsquo;est ainsi que je suis retomb\u00e9e \n<a class=\"moretag\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/\"> [...]<\/a>","protected":false},"author":1,"featured_media":4049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[156],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j&#039;avais envie de r\u00eaver un peu. C&#039;est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu&#039;est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j&#039;ai lu ce roman, c&#039;\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Eliwenn\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le blog d&#039;Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta property=\"og:description\" content=\"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j&#039;avais envie de r\u00eaver un peu. C&#039;est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu&#039;est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j&#039;ai lu ce roman, c&#039;\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-11T16:42:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-08-18T15:02:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j&#039;avais envie de r\u00eaver un peu. C&#039;est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu&#039;est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j&#039;ai lu ce roman, c&#039;\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#article\",\"name\":\"\\u00ab Jane Eyre \\u00bb de Charlotte Bront\\u00eb : romance et allumettes | Le blog d'Eliwenn\",\"headline\":\"\\u00ab\\u00a0Jane Eyre\\u00a0\\u00bb de Charlotte Bront\\u00eb : romance et allumettes\",\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/manor-2820106_1920.jpg\",\"width\":1920,\"height\":1280},\"datePublished\":\"2020-12-11T18:42:34+02:00\",\"dateModified\":\"2021-08-18T17:02:59+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#webpage\"},\"articleSection\":\"Une d\\u00e9voreuse de livres, roman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"position\":2,\"name\":\"Une d\\u00e9voreuse de livres\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#listItem\",\"name\":\"\\u00ab\\u00a0Jane Eyre\\u00a0\\u00bb de Charlotte Bront\\u00eb : romance et allumettes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#listItem\",\"position\":3,\"name\":\"\\u00ab\\u00a0Jane Eyre\\u00a0\\u00bb de Charlotte Bront\\u00eb : romance et allumettes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"Eliwenn\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#authorImage\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g\",\"width\":96,\"height\":96,\"caption\":\"Eliwenn\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#webpage\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/\",\"name\":\"\\u00ab Jane Eyre \\u00bb de Charlotte Bront\\u00eb : romance et allumettes | Le blog d'Eliwenn\",\"description\":\"Apr\\u00e8s avoir encha\\u00een\\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\\u00eatre, j'avais envie de r\\u00eaver un peu. C'est ainsi que je suis retomb\\u00e9e sur ce monument de romantisme qu'est Jane Eyre de Charlotte Bront\\u00eb. La premi\\u00e8re fois que j'ai lu ce roman, c'\\u00e9tait en anglais, au lyc\\u00e9e, il y a environ 15 ans. Inutile de\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/manor-2820106_1920.jpg\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#mainImage\",\"width\":1920,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/jane-eyre-charlotte-bronte\\\/#mainImage\"},\"datePublished\":\"2020-12-11T18:42:34+02:00\",\"dateModified\":\"2021-08-18T17:02:59+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d'Eliwenn","description":"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j'avais envie de r\u00eaver un peu. C'est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu'est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j'ai lu ce roman, c'\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de","canonical_url":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#article","name":"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d'Eliwenn","headline":"\u00ab\u00a0Jane Eyre\u00a0\u00bb de Charlotte Bront\u00eb : romance et allumettes","author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920.jpg","width":1920,"height":1280},"datePublished":"2020-12-11T18:42:34+02:00","dateModified":"2021-08-18T17:02:59+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#webpage"},"isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#webpage"},"articleSection":"Une d\u00e9voreuse de livres, roman"},{"@type":"BreadcrumbList","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","position":1,"name":"Domicile","item":"http:\/\/elsa-fachinetti.fr\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","position":2,"name":"Une d\u00e9voreuse de livres","item":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#listItem","name":"\u00ab\u00a0Jane Eyre\u00a0\u00bb de Charlotte Bront\u00eb : romance et allumettes"},"previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#listItem","position":3,"name":"\u00ab\u00a0Jane Eyre\u00a0\u00bb de Charlotte Bront\u00eb : romance et allumettes","previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}}]},{"@type":"Organization","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","url":"http:\/\/elsa-fachinetti.fr\/blog\/"},{"@type":"Person","@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author","url":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/","name":"Eliwenn","image":{"@type":"ImageObject","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#authorImage","url":"http:\/\/0.gravatar.com\/avatar\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g","width":96,"height":96,"caption":"Eliwenn"}},{"@type":"WebPage","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#webpage","url":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/","name":"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d'Eliwenn","description":"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j'avais envie de r\u00eaver un peu. C'est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu'est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j'ai lu ce roman, c'\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#breadcrumblist"},"author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2021\/08\/manor-2820106_1920.jpg","@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#mainImage","width":1920,"height":1280},"primaryImageOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/#mainImage"},"datePublished":"2020-12-11T18:42:34+02:00","dateModified":"2021-08-18T17:02:59+02:00"},{"@type":"WebSite","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website","url":"http:\/\/elsa-fachinetti.fr\/blog\/","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le blog d'Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","og:type":"article","og:title":"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d'Eliwenn","og:description":"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j'avais envie de r\u00eaver un peu. C'est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu'est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j'ai lu ce roman, c'\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de","og:url":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/","article:published_time":"2020-12-11T16:42:34+00:00","article:modified_time":"2021-08-18T15:02:59+00:00","twitter:card":"summary_large_image","twitter:title":"\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes | Le blog d'Eliwenn","twitter:description":"Apr\u00e8s avoir encha\u00een\u00e9 quelques romans dystopiques sur lesquels je reviendrai peut-\u00eatre, j'avais envie de r\u00eaver un peu. C'est ainsi que je suis retomb\u00e9e sur ce monument de romantisme qu'est Jane Eyre de Charlotte Bront\u00eb. La premi\u00e8re fois que j'ai lu ce roman, c'\u00e9tait en anglais, au lyc\u00e9e, il y a environ 15 ans. Inutile de"},"aioseo_meta_data":{"post_id":"4048","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-20 18:34:42","updated":"2025-06-04 01:26:13","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/\" title=\"Une d\u00e9voreuse de livres\">Une d\u00e9voreuse de livres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00ab Jane Eyre \u00bb de Charlotte Bront\u00eb : romance et allumettes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"http:\/\/elsa-fachinetti.fr\/blog"},{"label":"Une d\u00e9voreuse de livres","link":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/"},{"label":"\u00ab\u00a0Jane Eyre\u00a0\u00bb de Charlotte Bront\u00eb : romance et allumettes","link":"http:\/\/elsa-fachinetti.fr\/blog\/jane-eyre-charlotte-bronte\/"}],"_links":{"self":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/4048"}],"collection":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":2,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"predecessor-version":[{"id":4054,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/4048\/revisions\/4054"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media\/4049"}],"wp:attachment":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/tags?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}