
{"id":3245,"date":"2015-10-09T10:14:21","date_gmt":"2015-10-09T08:14:21","guid":{"rendered":"http:\/\/elsa-fachinetti.fr\/blog\/?p=3245"},"modified":"2016-01-16T20:32:35","modified_gmt":"2016-01-16T18:32:35","slug":"captive-une-bd-dont-vous-etes-le-heros","status":"publish","type":"post","link":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/","title":{"rendered":"Captive, une BD dont vous \u00eates le h\u00e9ros"},"content":{"rendered":"<p>Lorsque j&rsquo;\u00e9tais plus jeune, j&rsquo;adorais les fameux <strong>\u00ab\u00a0livres dont vous \u00eates le h\u00e9ros\u00a0\u00bb<\/strong>. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept.<\/p>\n<p>Depuis quelques ann\u00e9es, \u00a0les \u00e9ditions <strong>Makaka<\/strong> proposent des <strong>\u00ab\u00a0BD dont vous \u00eates le h\u00e9ros\u00a0\u00bb<\/strong>. Le principe est le m\u00eame que pour les LDVELH : g\u00e9n\u00e9ralement, une case \u00e9quivaut \u00e0 un paragraphe, avec un certain nombre de choix possibles. J&rsquo;ai fait une petite boulimie \u00e0 la d\u00e9couverte de cette collection et j&rsquo;en ai achet\u00e9 4 en une dizaine de jours :<\/p>\n<ul>\n<li><a href=\"http:\/\/www.makaka-editions.com\/2015\/07\/zombies\/\" target=\"_blank\">Zombies <\/a>: tr\u00e8s prenant mais dont les fins sont, je trouve, un peu rat\u00e9es. On ne sait jamais vraiment si on a gagn\u00e9 ou perdu et certaines cases sont purement et simplement des culs-de-sacs (pas de num\u00e9ro pour continuer ni de mot \u00ab\u00a0Fin\u00a0\u00bb).<\/li>\n<li><a href=\"http:\/\/www.makaka-editions.com\/2012\/06\/journal-dun-heros-chevaliers\/\" target=\"_blank\">Chevaliers <\/a>: d&rsquo;excellentes critiques qui proviennent, je pense, de parents ayant offerts ce tome \u00e0 leurs jeunes enfants. Quasiment jamais de choix : on avance, on avance, on avance, parfois on meurt. Pas int\u00e9ressant et on se retrouve souvent \u00e0 tourner en rond. Ma plus grosse d\u00e9ception.<\/li>\n<li><a href=\"http:\/\/www.makaka-editions.com\/2014\/04\/les-magiciens-du-fer\/\" target=\"_blank\">Les magiciens du fer <\/a>: une bonne BD dont vous \u00eates le h\u00e9ros. Les dessins sont jolis, l&rsquo;ambiance steampunk bien pr\u00e9sente&#8230; J&rsquo;ai un petit doute sur la rejouabilit\u00e9 car j&rsquo;ai eu l&rsquo;impression que les possibilit\u00e9s \u00e9taient parfois un peu limit\u00e9es. Enfin, pour la\u00a0refaire, il faudrait d\u00e9j\u00e0 que je parvienne\u00a0\u00e0 la terminer (sans mourir tragiquement).<\/li>\n<li><a href=\"http:\/\/www.makaka-editions.com\/2014\/10\/captive\/\" target=\"_blank\">Captive <\/a>: mon gros coup de coeur et la BD qui m&rsquo;a donn\u00e9 envie d&rsquo;\u00e9crire cet article. Mais de quoi s&rsquo;agit-il ?<\/li>\n<\/ul>\n<h2>Une aventure sombre aux fins multiples<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-3259\" src=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/10\/captive-bd-heros.jpg\" alt=\"captive-bd- dont vous etes le heros\" width=\"458\" height=\"639\" \/><\/p>\n<p>Dans <strong>Captive<\/strong>, vous incarnez un policier dont la fille vient d&rsquo;\u00eatre\u00a0enlev\u00e9e. Ses ravisseurs vous ont donn\u00e9 rendez-vous dans un manoir isol\u00e9, o\u00f9 vous devrez leur remettre une ran\u00e7on de 10 000 euros. Cependant, lorsque vous arrivez sur place avec deux coll\u00e8gues planqu\u00e9s, les choses d\u00e9g\u00e9n\u00e8rent. Vous voil\u00e0 donc dans cette immense b\u00e2tisse o\u00f9 vous n&rsquo;\u00eates pas le bienvenu et vous devez <strong>retrouver votre prog\u00e9niture<\/strong>. Vite.<\/p>\n<p>Les r\u00e8gles sont tr\u00e8s simples. Vous partez avec\u00a0un certain nombre de points de vie, qui\u00a0\u00e9volue\u00a0au fil de vos d\u00e9couvertes plus ou moins heureuses. Vous devez \u00e9galement g\u00e9rer votre temps soigneusement. Si vous \u00eates trop lent, vous ne parviendrez pas \u00e0 sauver votre fille. J&rsquo;en profite d&rsquo;ailleurs pour pr\u00e9ciser qu&rsquo;il y a plusieurs fins et que j&rsquo;ai probablement d\u00e9j\u00e0 eu la pire&#8230;<\/p>\n<p>Au fil de votre exploration, vous trouverez diff\u00e9rents objets qui vous aideront \u00e0 avancer, sachant que vous \u00eates limit\u00e9 \u00e0 3 \u00e0 la fois. Attention donc \u00e0 bien s\u00e9lectionner ce que vous gardez et ce que vous laissez sur place.<\/p>\n<p>Captive est une BD noire. L&rsquo;ambiance est pesante et vous ne savez jamais ce qui vous attend derri\u00e8re chaque porte que vous poussez. L&rsquo;histoire est prenante, les r\u00e8gles efficaces&#8230; Vous comprendrez vite qu&rsquo;un\u00a0myst\u00e8re entoure le manoir et que vous,\u00a0simple flic, \u00eates\u00a0m\u00eal\u00e9 \u00e0 une histoire qui d\u00e9passe le simple ran\u00e7onnage. Bref, sit\u00f4t la premi\u00e8re page tourn\u00e9e, vous aurez envie d&rsquo;aller jusqu&rsquo;au bout.<\/p>\n<p>Ces BD sont assez co\u00fbteuses (19 euros) mais vous ne regretterez s\u00fbrement pas l&rsquo;achat de Captive. Et pour ceux qui ne souhaitent pas gribouiller leur livre, Makaka met \u00e0 votre disposition la <a href=\"http:\/\/www.makaka-editions.com\/2015\/01\/les-goodies-de-captive\/\" target=\"_blank\">feuille de perso \u00e0 t\u00e9l\u00e9charger sur son site<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"Lorsque j&rsquo;\u00e9tais plus jeune, j&rsquo;adorais les fameux \u00ab\u00a0livres dont vous \u00eates le h\u00e9ros\u00a0\u00bb. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains \n<a class=\"moretag\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/\"> [...]<\/a>","protected":false},"author":1,"featured_media":3464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[372,15],"tags":[276,118],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lorsque j&#039;\u00e9tais plus jeune, j&#039;adorais les fameux &quot;livres dont vous \u00eates le h\u00e9ros&quot;. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Eliwenn\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le blog d&#039;Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta property=\"og:description\" content=\"Lorsque j&#039;\u00e9tais plus jeune, j&#039;adorais les fameux &quot;livres dont vous \u00eates le h\u00e9ros&quot;. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-09T08:14:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-16T18:32:35+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lorsque j&#039;\u00e9tais plus jeune, j&#039;adorais les fameux &quot;livres dont vous \u00eates le h\u00e9ros&quot;. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#article\",\"name\":\"Captive, une BD dont vous \\u00eates le h\\u00e9ros | Le blog d'Eliwenn\",\"headline\":\"Captive, une BD dont vous \\u00eates le h\\u00e9ros\",\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/captive-bd-heros2.jpg\",\"width\":516,\"height\":444},\"datePublished\":\"2015-10-09T10:14:21+02:00\",\"dateModified\":\"2016-01-16T20:32:35+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#webpage\"},\"articleSection\":\"Joueuse, Une d\\u00e9voreuse de livres, jeu de role, livre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"position\":2,\"name\":\"Une d\\u00e9voreuse de livres\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#listItem\",\"name\":\"Captive, une BD dont vous \\u00eates le h\\u00e9ros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#listItem\",\"position\":3,\"name\":\"Captive, une BD dont vous \\u00eates le h\\u00e9ros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"Eliwenn\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#authorImage\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g\",\"width\":96,\"height\":96,\"caption\":\"Eliwenn\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#webpage\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/\",\"name\":\"Captive, une BD dont vous \\u00eates le h\\u00e9ros | Le blog d'Eliwenn\",\"description\":\"Lorsque j'\\u00e9tais plus jeune, j'adorais les fameux \\\"livres dont vous \\u00eates le h\\u00e9ros\\\". Ils appartiennent malheureusement \\u00e0 une autre \\u00e9poque et, si certains ont \\u00e9t\\u00e9 r\\u00e9\\u00e9dit\\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \\u00e0 \\u00eatre nostalgique du concept. Depuis quelques ann\\u00e9es,\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/captive-bd-heros2.jpg\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#mainImage\",\"width\":516,\"height\":444},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/captive-une-bd-dont-vous-etes-le-heros\\\/#mainImage\"},\"datePublished\":\"2015-10-09T10:14:21+02:00\",\"dateModified\":\"2016-01-16T20:32:35+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d'Eliwenn","description":"Lorsque j'\u00e9tais plus jeune, j'adorais les fameux \"livres dont vous \u00eates le h\u00e9ros\". Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,","canonical_url":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#article","name":"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d'Eliwenn","headline":"Captive, une BD dont vous \u00eates le h\u00e9ros","author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/10\/captive-bd-heros2.jpg","width":516,"height":444},"datePublished":"2015-10-09T10:14:21+02:00","dateModified":"2016-01-16T20:32:35+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#webpage"},"isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#webpage"},"articleSection":"Joueuse, Une d\u00e9voreuse de livres, jeu de role, livre"},{"@type":"BreadcrumbList","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","position":1,"name":"Domicile","item":"http:\/\/elsa-fachinetti.fr\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","position":2,"name":"Une d\u00e9voreuse de livres","item":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#listItem","name":"Captive, une BD dont vous \u00eates le h\u00e9ros"},"previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#listItem","position":3,"name":"Captive, une BD dont vous \u00eates le h\u00e9ros","previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}}]},{"@type":"Organization","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","url":"http:\/\/elsa-fachinetti.fr\/blog\/"},{"@type":"Person","@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author","url":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/","name":"Eliwenn","image":{"@type":"ImageObject","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#authorImage","url":"http:\/\/0.gravatar.com\/avatar\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g","width":96,"height":96,"caption":"Eliwenn"}},{"@type":"WebPage","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#webpage","url":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/","name":"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d'Eliwenn","description":"Lorsque j'\u00e9tais plus jeune, j'adorais les fameux \"livres dont vous \u00eates le h\u00e9ros\". Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#breadcrumblist"},"author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/10\/captive-bd-heros2.jpg","@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#mainImage","width":516,"height":444},"primaryImageOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/#mainImage"},"datePublished":"2015-10-09T10:14:21+02:00","dateModified":"2016-01-16T20:32:35+02:00"},{"@type":"WebSite","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website","url":"http:\/\/elsa-fachinetti.fr\/blog\/","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le blog d'Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","og:type":"article","og:title":"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d'Eliwenn","og:description":"Lorsque j'\u00e9tais plus jeune, j'adorais les fameux &quot;livres dont vous \u00eates le h\u00e9ros&quot;. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,","og:url":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/","article:published_time":"2015-10-09T08:14:21+00:00","article:modified_time":"2016-01-16T18:32:35+00:00","twitter:card":"summary_large_image","twitter:title":"Captive, une BD dont vous \u00eates le h\u00e9ros | Le blog d'Eliwenn","twitter:description":"Lorsque j'\u00e9tais plus jeune, j'adorais les fameux &quot;livres dont vous \u00eates le h\u00e9ros&quot;. Ils appartiennent malheureusement \u00e0 une autre \u00e9poque et, si certains ont \u00e9t\u00e9 r\u00e9\u00e9dit\u00e9s en 2012 par Gallimard, ils ont disparu des rayons des librairies. Il semble pourtant que je ne sois pas la seule \u00e0 \u00eatre nostalgique du concept. Depuis quelques ann\u00e9es,"},"aioseo_meta_data":{"post_id":"3245","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-20 18:36:45","updated":"2025-06-04 01:16:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/\" title=\"Une d\u00e9voreuse de livres\">Une d\u00e9voreuse de livres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCaptive, une BD dont vous \u00eates le h\u00e9ros\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"http:\/\/elsa-fachinetti.fr\/blog"},{"label":"Une d\u00e9voreuse de livres","link":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/"},{"label":"Captive, une BD dont vous \u00eates le h\u00e9ros","link":"http:\/\/elsa-fachinetti.fr\/blog\/captive-une-bd-dont-vous-etes-le-heros\/"}],"_links":{"self":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3245"}],"collection":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/comments?post=3245"}],"version-history":[{"count":2,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3245\/revisions"}],"predecessor-version":[{"id":3268,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3245\/revisions\/3268"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media\/3464"}],"wp:attachment":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media?parent=3245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/categories?post=3245"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/tags?post=3245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}