
{"id":3151,"date":"2015-08-23T14:44:03","date_gmt":"2015-08-23T13:44:03","guid":{"rendered":"http:\/\/elsa-fachinetti.fr\/blog\/?p=3151"},"modified":"2016-01-16T20:38:42","modified_gmt":"2016-01-16T18:38:42","slug":"lecture-estivale-la-conjuration-primitive-de-maxime-chattam","status":"publish","type":"post","link":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/","title":{"rendered":"Lecture estivale : \u00ab\u00a0La conjuration primitive\u00a0\u00bb de Maxime Chattam"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-3175\" style=\"margin-left: 5px; margin-right: 5px;\" src=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/08\/9782226241405g.jpg\" alt=\"conjuration primitive avis\" width=\"223\" height=\"323\" \/>Je n&rsquo;ai encore jamais parl\u00e9 de <strong>Maxime Chattam<\/strong> sur ce blog et pourtant, il s&rsquo;agit sans aucun doute de l&rsquo;un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l&rsquo;ai d\u00e9couvert avec sa <strong>\u00ab\u00a0trilogie du mal\u00a0\u00bb<\/strong> il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec\u00a0beaucoup\u00a0de plaisir. Si vous aimez les <strong>polars<\/strong> qui vous tiennent en haleine d\u00e8s la premi\u00e8re page, voici un auteur incontournable.<\/p>\n<p>Cet \u00e9t\u00e9, j&rsquo;ai choisi de mettre <strong>\u00ab\u00a0La conjuration primitive\u00a0\u00bb<\/strong> dans mon sac de plage. Il s&rsquo;agit du premier roman d&rsquo;une autre trilogie, mettant en sc\u00e8ne la section de recherche (SR) de la gendarmerie de Paris. Le troisi\u00e8me et dernier opus sortira\u00a0l&rsquo;ann\u00e9e prochaine.<\/p>\n<p>Une fois encore, il nous met face \u00e0 la noirceur de l&rsquo;\u00eatre humain, en repoussant constamment les limites de l&rsquo;imaginable (et du tol\u00e9rable). \u00ab\u00a0La conjuration primitive\u00a0\u00bb\u00a0nous jette sur\u00a0les traces de deux psychopathes, <strong>la B\u00eate et le Fant\u00f4me<\/strong>, que tout semble opposer. Un seul \u00e9l\u00e9ment les relie l&rsquo;un \u00e0 l&rsquo;autre : le symbole *e, retrouv\u00e9 syst\u00e9matiquement grav\u00e9 sur le corps de leurs victimes. La SR\u00a0n&rsquo;a aucune piste et redoute de nouvelles victimes. Au point mort, elle fait appel \u00e0\u00a0Richard Mikelis, un grand criminologue d\u00e9sormais \u00e0 la retraite,\u00a0capable de penser comme un\u00a0meurtrier et de se fondre dans sa peau. Hant\u00e9 par les fant\u00f4mes de sa carri\u00e8re, il refuse dans un premier temps de leur apporter son aide. Mais lorsque le<strong> myst\u00e9rieux symbole *e<\/strong> est repris par d&rsquo;autres criminels, sa curiosit\u00e9 l&#8217;emporte&#8230;<\/p>\n<h2>Palpitant d\u00e8s la premi\u00e8re page<\/h2>\n<p>Je ne vais pas vous en dire plus pour ne pas risquer de vous spoiler. Tout ce que je peux ajouter, c&rsquo;est qu&rsquo;apr\u00e8s avoir lu les premi\u00e8res pages, vous ne pourrez plus l\u00e2cher ce roman. Cela va vite, tr\u00e8s vite ! La <strong>tension<\/strong> et le <strong>suspense<\/strong> sont pr\u00e9sents page apr\u00e8s page. Les 300 pages se d\u00e9vorent en un \u00e9clair, jusqu&rsquo;au terrible d\u00e9nouement auquel il est\u00a0impossible de se\u00a0pr\u00e9parer. Il ne m&rsquo;a fallu que deux apr\u00e8s-midis de farniente sur la plage pour le terminer. De plus, la construction du livre, en<strong> plusieurs parties<\/strong>, est assez surprenante et nous envoie\u00a0une bonne dose de stress. On comprend brutalement que TOUT\u00a0peut arriver.<\/p>\n<p>L&rsquo;ensemble du roman est bien document\u00e9. On sent que Maxime Chattam a suivi des \u00e9tudes de criminologie et qu&rsquo;il conna\u00eet son sujet sur le bout des doigts. Enfin, les personnages, Alexis et Ludivine en t\u00eate, sont charismatiques et font que l&rsquo;on s&rsquo;attache tr\u00e8s vite \u00e0 l&rsquo;\u00e9quipe. Cela nous implique \u00e9norm\u00e9ment\u00a0dans l&rsquo;histoire\u00a0et nous donne l&rsquo;impression de faire partie de la brigade. On\u00a0VIT l&rsquo;enqu\u00eate \u00e0 ses c\u00f4t\u00e9s jusqu&rsquo;\u00e0 la derni\u00e8re seconde et on ferme le livre \u00e0 regret.<\/p>\n<p>Pour combler le manque, j&rsquo;ai d\u00e9j\u00e0 entam\u00e9 la suite, <strong>\u00ab\u00a0La patience du diable\u00a0\u00bb<\/strong>, qui offre une narration toujours aussi tr\u00e9pidante.<\/p>\n<blockquote><p>Sur le web :\u00a0<a href=\"http:\/\/www.chattamistes.com\/forum\/\" target=\"_blank\">www.chattamistes.com<\/a>, un forum de fans sur lequel intervient r\u00e9guli\u00e8rement Maxime Chattam.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"Je n&rsquo;ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s&rsquo;agit sans aucun doute de l&rsquo;un de mes auteurs \n<a class=\"moretag\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/\"> [...]<\/a>","protected":false},"author":1,"featured_media":3467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[15],"tags":[119,156],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Je n&#039;ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s&#039;agit sans aucun doute de l&#039;un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l&#039;ai d\u00e9couvert avec sa &quot;trilogie du mal&quot; il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Eliwenn\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le blog d&#039;Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta property=\"og:description\" content=\"Je n&#039;ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s&#039;agit sans aucun doute de l&#039;un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l&#039;ai d\u00e9couvert avec sa &quot;trilogie du mal&quot; il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-08-23T13:44:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-01-16T18:38:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Je n&#039;ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s&#039;agit sans aucun doute de l&#039;un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l&#039;ai d\u00e9couvert avec sa &quot;trilogie du mal&quot; il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#article\",\"name\":\"Lecture estivale : \\u00ab La conjuration primitive \\u00bb de Maxime Chattam | Le blog d'Eliwenn\",\"headline\":\"Lecture estivale : \\u00ab\\u00a0La conjuration primitive\\u00a0\\u00bb de Maxime Chattam\",\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/maxime-chattam-conjuration-primitive1.jpg\",\"width\":379,\"height\":326},\"datePublished\":\"2015-08-23T14:44:03+02:00\",\"dateModified\":\"2016-01-16T20:38:42+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#webpage\"},\"articleSection\":\"Une d\\u00e9voreuse de livres, livres, roman\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"position\":2,\"name\":\"Une d\\u00e9voreuse de livres\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#listItem\",\"name\":\"Lecture estivale : \\u00ab\\u00a0La conjuration primitive\\u00a0\\u00bb de Maxime Chattam\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#listItem\",\"position\":3,\"name\":\"Lecture estivale : \\u00ab\\u00a0La conjuration primitive\\u00a0\\u00bb de Maxime Chattam\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/une-devoreuse-de-livres\\\/#listItem\",\"name\":\"Une d\\u00e9voreuse de livres\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"Eliwenn\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#authorImage\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g\",\"width\":96,\"height\":96,\"caption\":\"Eliwenn\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#webpage\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/\",\"name\":\"Lecture estivale : \\u00ab La conjuration primitive \\u00bb de Maxime Chattam | Le blog d'Eliwenn\",\"description\":\"Je n'ai encore jamais parl\\u00e9 de Maxime Chattam sur ce blog et pourtant, il s'agit sans aucun doute de l'un de mes auteurs pr\\u00e9f\\u00e9r\\u00e9s. Je l'ai d\\u00e9couvert avec sa \\\"trilogie du mal\\\" il y a quelques ann\\u00e9es et, depuis, je d\\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/maxime-chattam-conjuration-primitive1.jpg\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#mainImage\",\"width\":379,\"height\":326},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\\\/#mainImage\"},\"datePublished\":\"2015-08-23T14:44:03+02:00\",\"dateModified\":\"2016-01-16T20:38:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d'Eliwenn","description":"Je n'ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s'agit sans aucun doute de l'un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l'ai d\u00e9couvert avec sa \"trilogie du mal\" il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent","canonical_url":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#article","name":"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d'Eliwenn","headline":"Lecture estivale : \u00ab\u00a0La conjuration primitive\u00a0\u00bb de Maxime Chattam","author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/08\/maxime-chattam-conjuration-primitive1.jpg","width":379,"height":326},"datePublished":"2015-08-23T14:44:03+02:00","dateModified":"2016-01-16T20:38:42+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#webpage"},"isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#webpage"},"articleSection":"Une d\u00e9voreuse de livres, livres, roman"},{"@type":"BreadcrumbList","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","position":1,"name":"Domicile","item":"http:\/\/elsa-fachinetti.fr\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","position":2,"name":"Une d\u00e9voreuse de livres","item":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#listItem","name":"Lecture estivale : \u00ab\u00a0La conjuration primitive\u00a0\u00bb de Maxime Chattam"},"previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#listItem","position":3,"name":"Lecture estivale : \u00ab\u00a0La conjuration primitive\u00a0\u00bb de Maxime Chattam","previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/#listItem","name":"Une d\u00e9voreuse de livres"}}]},{"@type":"Organization","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","url":"http:\/\/elsa-fachinetti.fr\/blog\/"},{"@type":"Person","@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author","url":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/","name":"Eliwenn","image":{"@type":"ImageObject","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#authorImage","url":"http:\/\/0.gravatar.com\/avatar\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g","width":96,"height":96,"caption":"Eliwenn"}},{"@type":"WebPage","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#webpage","url":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/","name":"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d'Eliwenn","description":"Je n'ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s'agit sans aucun doute de l'un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l'ai d\u00e9couvert avec sa \"trilogie du mal\" il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#breadcrumblist"},"author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2015\/08\/maxime-chattam-conjuration-primitive1.jpg","@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#mainImage","width":379,"height":326},"primaryImageOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/#mainImage"},"datePublished":"2015-08-23T14:44:03+02:00","dateModified":"2016-01-16T20:38:42+02:00"},{"@type":"WebSite","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website","url":"http:\/\/elsa-fachinetti.fr\/blog\/","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le blog d'Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","og:type":"article","og:title":"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d'Eliwenn","og:description":"Je n'ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s'agit sans aucun doute de l'un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l'ai d\u00e9couvert avec sa &quot;trilogie du mal&quot; il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent","og:url":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/","article:published_time":"2015-08-23T13:44:03+00:00","article:modified_time":"2016-01-16T18:38:42+00:00","twitter:card":"summary_large_image","twitter:title":"Lecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam | Le blog d'Eliwenn","twitter:description":"Je n'ai encore jamais parl\u00e9 de Maxime Chattam sur ce blog et pourtant, il s'agit sans aucun doute de l'un de mes auteurs pr\u00e9f\u00e9r\u00e9s. Je l'ai d\u00e9couvert avec sa &quot;trilogie du mal&quot; il y a quelques ann\u00e9es et, depuis, je d\u00e9vore chacun de ses romans avec beaucoup de plaisir. Si vous aimez les polars qui vous tiennent"},"aioseo_meta_data":{"post_id":"3151","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-20 18:37:33","updated":"2025-06-04 01:16:28","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/\" title=\"Une d\u00e9voreuse de livres\">Une d\u00e9voreuse de livres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLecture estivale : \u00ab La conjuration primitive \u00bb de Maxime Chattam\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"http:\/\/elsa-fachinetti.fr\/blog"},{"label":"Une d\u00e9voreuse de livres","link":"http:\/\/elsa-fachinetti.fr\/blog\/category\/une-devoreuse-de-livres\/"},{"label":"Lecture estivale : \u00ab\u00a0La conjuration primitive\u00a0\u00bb de Maxime Chattam","link":"http:\/\/elsa-fachinetti.fr\/blog\/lecture-estivale-la-conjuration-primitive-de-maxime-chattam\/"}],"_links":{"self":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3151"}],"collection":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/comments?post=3151"}],"version-history":[{"count":2,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3151\/revisions"}],"predecessor-version":[{"id":3194,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/3151\/revisions\/3194"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media\/3467"}],"wp:attachment":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media?parent=3151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/categories?post=3151"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/tags?post=3151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}