
{"id":2486,"date":"2012-01-22T11:34:04","date_gmt":"2012-01-22T10:34:04","guid":{"rendered":"http:\/\/elsa-fachinetti.fr\/blog\/?p=2486"},"modified":"2012-01-22T11:34:04","modified_gmt":"2012-01-22T10:34:04","slug":"les-japonais-maitres-de-lepouvante","status":"publish","type":"post","link":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/","title":{"rendered":"Les japonais, ma\u00eetres de l&rsquo;\u00e9pouvante ?"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-full wp-image-2499\" style=\"margin: 5px;\" title=\"The-grudge\" src=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2012\/01\/The-grudge.jpg\" alt=\"\" width=\"224\" height=\"320\" srcset=\"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2012\/01\/The-grudge.jpg 280w, http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2012\/01\/The-grudge-210x300.jpg 210w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/>J&rsquo;adore les<strong> films d&rsquo;\u00e9pouvante japonais<\/strong>. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n&rsquo;est pas que dans le cin\u00e9ma, d&rsquo;ailleurs&#8230; Il me suffit de repenser aux livres <a title=\"\u00ab\u00a0Out\u00a0\u00bb : Le jeu du chat et de la souris version japonaise\u2026\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/2009\/07\/out-le-jeu-du-chat-et-de-la-souris-version-japonaise\/\">Out<\/a> ou <a title=\"\u00cates-vous pr\u00eat pour la Battle Royale ?\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/2009\/04\/battle-royale-avez-vous-deja-tue-votre-meilleur-ami\/\">Battle Royale<\/a>.)<\/p>\n<p>Dans les films d&rsquo;\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie adepte des massacres sanglants pour son simple plaisir. Le meurtrier est bien souvent un <strong>esprit tourment\u00e9<\/strong> qui crie vengeance, une entit\u00e9 contre laquelle on ne peut lutter. Et <strong>c&rsquo;est de cette impuissance que jaillissent l&rsquo;angoisse et le malaise<\/strong>. Une fois les personnages pi\u00e9g\u00e9s, il n&rsquo;y a pas de Happy End possible. De la cassette video tueuse de Ringu (Le Cercle pour le remake am\u00e9ricain) \u00e0 la maison hant\u00e9e de The Grudge, les histoires m\u00ealent legendes anciennes et l\u00e9gendes urbaines pour nous faire fr\u00e9mir.<\/p>\n<h2>R\u00e9incarnation et esprit tortur\u00e9<\/h2>\n<p>Le dernier film japonais que j&rsquo;ai regard\u00e9 a \u00e9t\u00e9 r\u00e9alis\u00e9 par Takashi Shimizu, celui-l\u00e0 m\u00eame qui a r\u00e9alis\u00e9 Th\u00e9 Grudge, The Grudge 2 et leurs remakes respectifs avec Sarah Michelle Gellar. <strong>R\u00e9incarnation<\/strong> (Rinne) prend place au coeur d&rsquo;un h\u00f4tel \u00e0 l&rsquo;abandon, th\u00e9\u00e2tre d&rsquo;un massacre 20 ans plus t\u00f4t. Un professeur d&rsquo;universit\u00e9, pris d&rsquo;une apparente crise de folie, avait tu\u00e9 11 personnes, personnel et clients, tout en filmant ses actes.<br \/>\nEt voila qu&rsquo;un r\u00e9alisateur d\u00e9cide d&rsquo;<strong>adapter cette sordide histoire<\/strong> au cin\u00e9ma. L&rsquo;actrice Nagisa Sugiura est s\u00e9lectionn\u00e9e pour jouer le r\u00f4le de la fille du professeur, l&rsquo;une des victimes. D\u00e8s lors, elle est prise de terribles <strong>visions et cauchemars<\/strong> dans lesquels elle se retrouve dans la peau de la petite fille. Une situation qui va s&rsquo;aggraver lorsque le r\u00e9alisateur choisit d&#8217;emmener toute l&rsquo;\u00e9quipe sur les lieux du drame, pour que ses acteurs s&rsquo;impregnent de l&rsquo;ambiance&#8230;<\/p>\n<div id=\"blogvision\" style=\"width: 625px; height: 490px;\">\n<object width=\"100%\" height=\"100%\"><param name=\"movie\" value=\"http:\/\/www.allocine.fr\/blogvision\/18742347\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><embed type=\"application\/x-shockwave-flash\" width=\"100%\" height=\"100%\" src=\"http:\/\/www.allocine.fr\/blogvision\/18742347\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/div>\n<p><\/p>\n<h2>Un style bien \u00e0 eux<\/h2>\n<p>Les films japonais ont un <strong>style assez particulier<\/strong>. Alors que les films am\u00e9ricains adorent inonder l&rsquo;\u00e9cran d&rsquo;hemoglobine, de tripes et de personnages hurlants, ils misent sur l&rsquo;ambiance et l&rsquo;\u00e9motion. La culture asiatique n&rsquo;est en rien comparable \u00e0 la culture am\u00e9ricaine, voire occidentale, et c&rsquo;est bien \u00e0 travers le cin\u00e9ma que c&rsquo;est le plus \u00e9vident. Ici, tr\u00e8s <strong>peu d&rsquo;effets sp\u00e9ciaux<\/strong>, on joue sur le maquillage et les d\u00e9cors. Certains trouveront \u00e7a ridicule, mais je pense que c&rsquo;est ce qui donne tout leur charme \u00e0 ces films. D&rsquo;autres moqueront le surjeu des acteurs et les situations parfois trop clich\u00e9. Mais oui, c&rsquo;est aussi \u00e7a, le cin\u00e9ma asiatique. Il faut parfois \u00eatre capable de prendre du recul et accepter de sortir des sentiers battus pour appr\u00e9cier.<\/p>\n<p>Si vous avez envie de plonger dans un film d&rsquo;\u00e9pouvante japonais, essayez donc <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=29346.html\">Ringu<\/a>, dont le remake avec Naomi Watts est tout aussi effrayant. <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=42552.html\">Le Cercle<\/a> est d&rsquo;ailleurs LE film qui m&rsquo;a fait m&rsquo;int\u00e9resser au cin\u00e9ma d&rsquo;horreur japonais. Essayez \u00e9galement <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=55429.html\">The Grudge<\/a>, dont le remake en est la copie conforme (seuls les acteurs changent), <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=108512.html\">La mort en ligne<\/a>, <a href=\"http:\/\/www.allocine.fr\/film\/fichefilm_gen_cfilm=125724.html\">Spirits<\/a>&#8230; Et plongez-vous dans de sombres histoires peupl\u00e9es de fant\u00f4mes malfaisants et de personnages d\u00e9pass\u00e9s par les \u00e9v\u00e8nements.<\/p>\n","protected":false},"excerpt":{"rendered":"J&rsquo;adore les films d&rsquo;\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. \n<a class=\"moretag\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/\"> [...]<\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[245,371],"tags":[54,337,369],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"J&#039;adore les films d&#039;\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n&#039;est pas que dans le cin\u00e9ma, d&#039;ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d&#039;\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Eliwenn\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Le blog d&#039;Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta property=\"og:description\" content=\"J&#039;adore les films d&#039;\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n&#039;est pas que dans le cin\u00e9ma, d&#039;ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d&#039;\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-01-22T10:34:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2012-01-22T10:34:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d&#039;Eliwenn\" \/>\n\t\t<meta name=\"twitter:description\" content=\"J&#039;adore les films d&#039;\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n&#039;est pas que dans le cin\u00e9ma, d&#039;ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d&#039;\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#article\",\"name\":\"Les japonais, ma\\u00eetres de l\\u2019\\u00e9pouvante ? | Le blog d'Eliwenn\",\"headline\":\"Les japonais, ma\\u00eetres de l&rsquo;\\u00e9pouvante ?\",\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/The-grudge.jpg\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#articleImage\",\"width\":280,\"height\":400},\"datePublished\":\"2012-01-22T11:34:04+02:00\",\"dateModified\":\"2012-01-22T11:34:04+02:00\",\"inLanguage\":\"fr-FR\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#webpage\"},\"articleSection\":\"Cin\\u00e9phile, Passionn\\u00e9e de culture asiatique, cin\\u00e9ma, film d'?pouvante, films japonais\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/cinephile\\\/#listItem\",\"name\":\"Cin\\u00e9phile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/cinephile\\\/#listItem\",\"position\":2,\"name\":\"Cin\\u00e9phile\",\"item\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/cinephile\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#listItem\",\"name\":\"Les japonais, ma\\u00eetres de l&rsquo;\\u00e9pouvante ?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#listItem\",\"position\":3,\"name\":\"Les japonais, ma\\u00eetres de l&rsquo;\\u00e9pouvante ?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/category\\\/cinephile\\\/#listItem\",\"name\":\"Cin\\u00e9phile\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/\",\"name\":\"Eliwenn\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#authorImage\",\"url\":\"http:\\\/\\\/0.gravatar.com\\\/avatar\\\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g\",\"width\":96,\"height\":96,\"caption\":\"Eliwenn\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#webpage\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/\",\"name\":\"Les japonais, ma\\u00eetres de l\\u2019\\u00e9pouvante ? | Le blog d'Eliwenn\",\"description\":\"J'adore les films d'\\u00e9pouvante japonais. Les japonais ont cette capacit\\u00e9 \\u00e0 imaginer des histoires terrifiantes qui me font syst\\u00e9matiquement froid dans le dos. (Ce n'est pas que dans le cin\\u00e9ma, d'ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d'\\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\\u00e9rie\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/les-japonais-maitres-de-lepouvante\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2012-01-22T11:34:04+02:00\",\"dateModified\":\"2012-01-22T11:34:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/\",\"name\":\"Le blog d'Eliwenn\",\"description\":\"Livres, jeux vid\\u00e9os ind\\u00e9s et d\\u00e9couvertes en tous genres !\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/elsa-fachinetti.fr\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d'Eliwenn","description":"J'adore les films d'\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n'est pas que dans le cin\u00e9ma, d'ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d'\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie","canonical_url":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#article","name":"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d'Eliwenn","headline":"Les japonais, ma\u00eetres de l&rsquo;\u00e9pouvante ?","author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/elsa-fachinetti.fr\/blog\/wp-content\/uploads\/2012\/01\/The-grudge.jpg","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#articleImage","width":280,"height":400},"datePublished":"2012-01-22T11:34:04+02:00","dateModified":"2012-01-22T11:34:04+02:00","inLanguage":"fr-FR","commentCount":2,"mainEntityOfPage":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#webpage"},"isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#webpage"},"articleSection":"Cin\u00e9phile, Passionn\u00e9e de culture asiatique, cin\u00e9ma, film d'?pouvante, films japonais"},{"@type":"BreadcrumbList","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","position":1,"name":"Domicile","item":"http:\/\/elsa-fachinetti.fr\/blog","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/#listItem","name":"Cin\u00e9phile"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/#listItem","position":2,"name":"Cin\u00e9phile","item":"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/","nextItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#listItem","name":"Les japonais, ma\u00eetres de l&rsquo;\u00e9pouvante ?"},"previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#listItem","position":3,"name":"Les japonais, ma\u00eetres de l&rsquo;\u00e9pouvante ?","previousItem":{"@type":"ListItem","@id":"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/#listItem","name":"Cin\u00e9phile"}}]},{"@type":"Organization","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","url":"http:\/\/elsa-fachinetti.fr\/blog\/"},{"@type":"Person","@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author","url":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/","name":"Eliwenn","image":{"@type":"ImageObject","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#authorImage","url":"http:\/\/0.gravatar.com\/avatar\/9dd3af5f69b90fab6584a70f3588b67b?s=96&d=wavatar&r=g","width":96,"height":96,"caption":"Eliwenn"}},{"@type":"WebPage","@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#webpage","url":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/","name":"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d'Eliwenn","description":"J'adore les films d'\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n'est pas que dans le cin\u00e9ma, d'ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d'\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/#breadcrumblist"},"author":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/author\/admin\/#author"},"datePublished":"2012-01-22T11:34:04+02:00","dateModified":"2012-01-22T11:34:04+02:00"},{"@type":"WebSite","@id":"http:\/\/elsa-fachinetti.fr\/blog\/#website","url":"http:\/\/elsa-fachinetti.fr\/blog\/","name":"Le blog d'Eliwenn","description":"Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/elsa-fachinetti.fr\/blog\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Le blog d'Eliwenn | Livres, jeux vid\u00e9os ind\u00e9s et d\u00e9couvertes en tous genres !","og:type":"article","og:title":"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d'Eliwenn","og:description":"J'adore les films d'\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n'est pas que dans le cin\u00e9ma, d'ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d'\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie","og:url":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/","article:published_time":"2012-01-22T10:34:04+00:00","article:modified_time":"2012-01-22T10:34:04+00:00","twitter:card":"summary_large_image","twitter:title":"Les japonais, ma\u00eetres de l\u2019\u00e9pouvante ? | Le blog d'Eliwenn","twitter:description":"J'adore les films d'\u00e9pouvante japonais. Les japonais ont cette capacit\u00e9 \u00e0 imaginer des histoires terrifiantes qui me font syst\u00e9matiquement froid dans le dos. (Ce n'est pas que dans le cin\u00e9ma, d'ailleurs... Il me suffit de repenser aux livres Out ou Battle Royale.) Dans les films d'\u00e9pouvante japonais, vous ne trouverez pas de tueur en s\u00e9rie"},"aioseo_meta_data":{"post_id":"2486","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-20 18:44:40","updated":"2025-06-04 00:48:50","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/\" title=\"Cin\u00e9phile\">Cin\u00e9phile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLes japonais, ma\u00eetres de l\u2019\u00e9pouvante ?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"http:\/\/elsa-fachinetti.fr\/blog"},{"label":"Cin\u00e9phile","link":"http:\/\/elsa-fachinetti.fr\/blog\/category\/cinephile\/"},{"label":"Les japonais, ma\u00eetres de l&rsquo;\u00e9pouvante ?","link":"http:\/\/elsa-fachinetti.fr\/blog\/les-japonais-maitres-de-lepouvante\/"}],"_links":{"self":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/2486"}],"collection":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/comments?post=2486"}],"version-history":[{"count":0,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/posts\/2486\/revisions"}],"wp:attachment":[{"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/media?parent=2486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/categories?post=2486"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elsa-fachinetti.fr\/blog\/wp-json\/wp\/v2\/tags?post=2486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}